{"id":45387,"date":"2024-02-21T04:48:22","date_gmt":"2024-02-21T04:48:22","guid":{"rendered":"https:\/\/z3asyd7ov7.onrocket.site\/?post_type=product&#038;p=45387"},"modified":"2024-02-21T05:57:39","modified_gmt":"2024-02-21T05:57:39","slug":"vigert-dw63nc-pipe-bending-machine","status":"publish","type":"product","link":"https:\/\/www.vigert.com\/th\/product\/vigert-dw63nc-pipe-bending-machine\/","title":{"rendered":"\u0e02\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e31\u0e14\u0e17\u0e48\u0e2d VIGERT DW63NC \u0e21\u0e37\u0e2d\u0e2a\u0e2d\u0e07"},"content":{"rendered":"<p>A VIGERT DW63NC Pipe Bending Machine is a piece of industrial equipment used to bend pipes or tubes into various shapes and angles. These machines are commonly used in industries such as construction, automotive, plumbing, and manufacturing. Here&#8217;s a description of a typical VIGERT DW63NC Pipe Bending Machine:<\/p>\n<ol>\n<li><strong>\u0e01\u0e23\u0e2d\u0e1a\u0e41\u0e25\u0e30\u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07<\/strong>: \u0e42\u0e14\u0e22\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b\u0e15\u0e31\u0e27\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e30\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e14\u0e49\u0e27\u0e22\u0e42\u0e04\u0e23\u0e07\u0e17\u0e35\u0e48\u0e41\u0e02\u0e47\u0e07\u0e41\u0e23\u0e07\u0e17\u0e33\u0e08\u0e32\u0e01\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e2b\u0e23\u0e37\u0e2d\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e17\u0e35\u0e48\u0e17\u0e19\u0e17\u0e32\u0e19\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e40\u0e1f\u0e23\u0e21\u0e43\u0e2b\u0e49\u0e01\u0e32\u0e23\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07\u0e43\u0e19\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e14\u0e31\u0e14\u0e07\u0e2d<\/li>\n<li><strong>\u0e01\u0e25\u0e44\u0e01\u0e01\u0e32\u0e23\u0e14\u0e31\u0e14<\/strong>: \u0e01\u0e25\u0e44\u0e01\u0e01\u0e32\u0e23\u0e14\u0e31\u0e14\u0e07\u0e2d\u0e02\u0e2d\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e14\u0e49\u0e27\u0e22\u0e41\u0e21\u0e48\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e14\u0e31\u0e14\u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e41\u0e23\u0e07\u0e01\u0e31\u0e1a\u0e17\u0e48\u0e2d\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e23\u0e39\u0e1b\u0e43\u0e2b\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e23\u0e39\u0e1b\u0e17\u0e23\u0e07\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e14\u0e31\u0e14\u0e07\u0e2d\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e1b\u0e23\u0e31\u0e1a\u0e41\u0e15\u0e48\u0e07\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e21\u0e38\u0e21\u0e42\u0e04\u0e49\u0e07\u0e07\u0e2d\u0e41\u0e25\u0e30\u0e23\u0e31\u0e28\u0e21\u0e35\u0e17\u0e35\u0e48\u0e41\u0e15\u0e01\u0e15\u0e48\u0e32\u0e07\u0e01\u0e31\u0e19\u0e44\u0e14\u0e49<\/li>\n<li><strong>\u0e23\u0e30\u0e1a\u0e1a\u0e2b\u0e19\u0e35\u0e1a<\/strong>: \u0e21\u0e35\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e23\u0e30\u0e1a\u0e1a\u0e08\u0e31\u0e1a\u0e22\u0e36\u0e14\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e22\u0e36\u0e14\u0e17\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e40\u0e02\u0e49\u0e32\u0e17\u0e35\u0e48\u0e43\u0e19\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e14\u0e31\u0e14 \u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e44\u0e21\u0e48\u0e43\u0e2b\u0e49\u0e25\u0e37\u0e48\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07 \u0e41\u0e04\u0e25\u0e21\u0e1b\u0e4c\u0e2d\u0e32\u0e08\u0e40\u0e1b\u0e47\u0e19\u0e41\u0e1a\u0e1a\u0e41\u0e21\u0e19\u0e19\u0e27\u0e25\u0e2b\u0e23\u0e37\u0e2d\u0e41\u0e1a\u0e1a\u0e44\u0e2e\u0e14\u0e23\u0e2d\u0e25\u0e34\u0e01 \u0e02\u0e36\u0e49\u0e19\u0e2d\u0e22\u0e39\u0e48\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e02\u0e2d\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23<\/li>\n<li><strong>\u0e27\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e14\u0e31\u0e14<\/strong>: VIGERT DW63NC Pipe Bending Machines employ various bending methods, including:\n<ul>\n<li>\u0e01\u0e32\u0e23\u0e14\u0e31\u0e14\u0e07\u0e2d\u0e41\u0e1a\u0e1a\u0e2b\u0e21\u0e38\u0e19: \u0e43\u0e19\u0e27\u0e34\u0e18\u0e35\u0e19\u0e35\u0e49 \u0e17\u0e48\u0e2d\u0e08\u0e30\u0e16\u0e39\u0e01\u0e25\u0e32\u0e01\u0e44\u0e1b\u0e23\u0e2d\u0e1a\u0e46 \u0e41\u0e21\u0e48\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e14\u0e31\u0e14\u0e41\u0e1a\u0e1a\u0e2d\u0e22\u0e39\u0e48\u0e01\u0e31\u0e1a\u0e17\u0e35\u0e48 \u0e43\u0e19\u0e02\u0e13\u0e30\u0e17\u0e35\u0e48\u0e41\u0e21\u0e48\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e14\u0e31\u0e14\u0e41\u0e1a\u0e1a\u0e2b\u0e21\u0e38\u0e19\u0e08\u0e30\u0e43\u0e0a\u0e49\u0e41\u0e23\u0e07\u0e43\u0e19\u0e01\u0e32\u0e23\u0e14\u0e31\u0e14\u0e17\u0e48\u0e2d<\/li>\n<li>\u0e01\u0e32\u0e23\u0e14\u0e31\u0e14\u0e41\u0e21\u0e19\u0e40\u0e14\u0e23\u0e25: \u0e43\u0e2a\u0e48\u0e41\u0e21\u0e19\u0e40\u0e14\u0e23\u0e25 (\u0e41\u0e01\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e48\u0e27\u0e19\u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e35\u0e48\u0e22\u0e37\u0e14\u0e2b\u0e22\u0e38\u0e48\u0e19\u0e44\u0e14\u0e49) \u0e40\u0e02\u0e49\u0e32\u0e44\u0e1b\u0e43\u0e19\u0e17\u0e48\u0e2d\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e44\u0e21\u0e48\u0e43\u0e2b\u0e49\u0e22\u0e38\u0e1a\u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e48\u0e19\u0e43\u0e19\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e14\u0e31\u0e14 \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e42\u0e04\u0e49\u0e07\u0e07\u0e2d\u0e44\u0e14\u0e49\u0e41\u0e19\u0e48\u0e19\u0e02\u0e36\u0e49\u0e19\u0e42\u0e14\u0e22\u0e21\u0e35\u0e01\u0e32\u0e23\u0e1a\u0e34\u0e14\u0e40\u0e1a\u0e37\u0e2d\u0e19\u0e19\u0e49\u0e2d\u0e22\u0e25\u0e07<\/li>\n<li>\u0e01\u0e32\u0e23\u0e14\u0e31\u0e14\u0e42\u0e04\u0e49\u0e07: \u0e27\u0e34\u0e18\u0e35\u0e19\u0e35\u0e49\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e17\u0e48\u0e2d\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e0a\u0e38\u0e14\u0e25\u0e39\u0e01\u0e01\u0e25\u0e34\u0e49\u0e07\u0e0b\u0e36\u0e48\u0e07\u0e08\u0e30\u0e04\u0e48\u0e2d\u0e22\u0e46 \u0e42\u0e04\u0e49\u0e07\u0e07\u0e2d\u0e43\u0e2b\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e23\u0e39\u0e1b\u0e23\u0e48\u0e32\u0e07<\/li>\n<\/ul>\n<\/li>\n<li><strong>\u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21<\/strong>\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e31\u0e14\u0e17\u0e48\u0e2d\u0e2a\u0e21\u0e31\u0e22\u0e43\u0e2b\u0e21\u0e48\u0e2b\u0e25\u0e32\u0e22\u0e23\u0e38\u0e48\u0e19\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e40\u0e0a\u0e34\u0e07\u0e15\u0e31\u0e27\u0e40\u0e25\u0e02\u0e14\u0e49\u0e27\u0e22\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c (CNC) \u0e17\u0e35\u0e48\u0e0a\u0e48\u0e27\u0e22\u0e43\u0e2b\u0e49\u0e1c\u0e39\u0e49\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e15\u0e31\u0e49\u0e07\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e41\u0e25\u0e30\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e14\u0e31\u0e14\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e41\u0e21\u0e48\u0e19\u0e22\u0e33 \u0e23\u0e30\u0e1a\u0e1a CNC \u0e0a\u0e48\u0e27\u0e22\u0e43\u0e2b\u0e49\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e25\u0e33\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e14\u0e31\u0e14\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34\u0e41\u0e25\u0e30\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e01\u0e32\u0e23\u0e14\u0e31\u0e14\u0e17\u0e35\u0e48\u0e2a\u0e21\u0e48\u0e33\u0e40\u0e2a\u0e21\u0e2d<\/li>\n<li><strong>\u0e01\u0e32\u0e23\u0e27\u0e31\u0e14\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21<\/strong>: \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e31\u0e14\u0e17\u0e48\u0e2d\u0e1a\u0e32\u0e07\u0e23\u0e38\u0e48\u0e19\u0e21\u0e35\u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e32\u0e23\u0e27\u0e31\u0e14\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e43\u0e19\u0e15\u0e31\u0e27\u0e17\u0e35\u0e48\u0e27\u0e31\u0e14\u0e21\u0e38\u0e21\u0e42\u0e04\u0e49\u0e07\u0e07\u0e2d \u0e23\u0e31\u0e28\u0e21\u0e35 \u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e22\u0e32\u0e27\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e41\u0e21\u0e48\u0e19\u0e22\u0e33 \u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e2b\u0e25\u0e48\u0e32\u0e19\u0e35\u0e49\u0e0a\u0e48\u0e27\u0e22\u0e43\u0e2b\u0e49\u0e41\u0e19\u0e48\u0e43\u0e08\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e42\u0e04\u0e49\u0e07\u0e07\u0e2d\u0e17\u0e35\u0e48\u0e40\u0e2a\u0e23\u0e47\u0e08\u0e2a\u0e21\u0e1a\u0e39\u0e23\u0e13\u0e4c\u0e19\u0e31\u0e49\u0e19\u0e15\u0e23\u0e07\u0e15\u0e32\u0e21\u0e02\u0e49\u0e2d\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e17\u0e35\u0e48\u0e01\u0e33\u0e2b\u0e19\u0e14<\/li>\n<li><strong>\u0e04\u0e38\u0e13\u0e25\u0e31\u0e01\u0e29\u0e13\u0e30\u0e14\u0e49\u0e32\u0e19\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22<\/strong>: \u0e04\u0e38\u0e13\u0e25\u0e31\u0e01\u0e29\u0e13\u0e30\u0e14\u0e49\u0e32\u0e19\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 \u0e40\u0e0a\u0e48\u0e19 \u0e1b\u0e38\u0e48\u0e21\u0e2b\u0e22\u0e38\u0e14\u0e09\u0e38\u0e01\u0e40\u0e09\u0e34\u0e19 \u0e01\u0e32\u0e23\u0e4c\u0e14\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19 \u0e41\u0e25\u0e30\u0e25\u0e39\u0e01\u0e42\u0e0b\u0e48 \u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e02\u0e2d\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e31\u0e14\u0e17\u0e48\u0e2d\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e2d\u0e38\u0e1a\u0e31\u0e15\u0e34\u0e40\u0e2b\u0e15\u0e38\u0e41\u0e25\u0e30\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e21\u0e31\u0e48\u0e19\u0e43\u0e08\u0e43\u0e19\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e02\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19<\/li>\n<li><strong>\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21<\/strong>: VIGERT DW63NC Pipe Bending Machines may come with a range of tooling options and accessories to accommodate different pipe sizes, materials, and bending requirements. This includes interchangeable bending dies, mandrels, and support rollers.<\/li>\n<li><strong>\u0e04\u0e27\u0e32\u0e21\u0e08\u0e38<\/strong>: \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e31\u0e14\u0e17\u0e48\u0e2d\u0e21\u0e35\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e15\u0e01\u0e15\u0e48\u0e32\u0e07\u0e01\u0e31\u0e19\u0e44\u0e1b \u0e42\u0e14\u0e22\u0e1a\u0e32\u0e07\u0e23\u0e38\u0e48\u0e19\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e21\u0e32\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e48\u0e2d\u0e17\u0e35\u0e48\u0e21\u0e35\u0e40\u0e2a\u0e49\u0e19\u0e1c\u0e48\u0e32\u0e19\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e01\u0e25\u0e32\u0e07\u0e40\u0e25\u0e47\u0e01\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e41\u0e25\u0e30\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e17\u0e35\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e14\u0e31\u0e14\u0e17\u0e48\u0e2d\u0e17\u0e35\u0e48\u0e21\u0e35\u0e40\u0e2a\u0e49\u0e19\u0e1c\u0e48\u0e32\u0e19\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e01\u0e25\u0e32\u0e07\u0e02\u0e19\u0e32\u0e14\u0e43\u0e2b\u0e0d\u0e48\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e15\u0e16\u0e38\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e17\u0e32\u0e07\u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e17\u0e32\u0e07\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21<\/li>\n<li><strong>\u0e01\u0e32\u0e23\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23<\/strong>: \u0e01\u0e32\u0e23\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e17\u0e35\u0e48\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e21\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2a\u0e21\u0e48\u0e33\u0e40\u0e2a\u0e21\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e34\u0e48\u0e07\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e43\u0e19\u0e23\u0e30\u0e22\u0e30\u0e22\u0e32\u0e27\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e19\u0e48\u0e32\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e16\u0e37\u0e2d\u0e02\u0e2d\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e31\u0e14\u0e17\u0e48\u0e2d \u0e0b\u0e36\u0e48\u0e07\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e2b\u0e25\u0e48\u0e2d\u0e25\u0e37\u0e48\u0e19 \u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e2a\u0e48\u0e27\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e17\u0e35\u0e48\u0e2a\u0e33\u0e04\u0e31\u0e0d \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e17\u0e35\u0e48\u0e2a\u0e36\u0e01\u0e2b\u0e23\u0e2d\u0e15\u0e32\u0e21\u0e40\u0e27\u0e25\u0e32\u0e17\u0e35\u0e48\u0e01\u0e33\u0e2b\u0e19\u0e14<\/li>\n<\/ol>\n<p>\u0e42\u0e14\u0e22\u0e2a\u0e23\u0e38\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e31\u0e14\u0e17\u0e48\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e2d\u0e40\u0e19\u0e01\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e17\u0e35\u0e48\u0e02\u0e32\u0e14\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e02\u0e36\u0e49\u0e19\u0e23\u0e39\u0e1b\u0e17\u0e48\u0e2d\u0e41\u0e25\u0e30\u0e17\u0e48\u0e2d\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e15\u0e2d\u0e1a\u0e2a\u0e19\u0e2d\u0e07\u0e04\u0e27\u0e32\u0e21\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22 \u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e01\u0e32\u0e23\u0e14\u0e31\u0e14\u0e41\u0e1a\u0e1a\u0e07\u0e48\u0e32\u0e22\u0e46 \u0e44\u0e1b\u0e08\u0e19\u0e16\u0e36\u0e07\u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e35\u0e48\u0e0b\u0e31\u0e1a\u0e0b\u0e49\u0e2d\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e31\u0e14\u0e40\u0e2b\u0e25\u0e48\u0e32\u0e19\u0e35\u0e49\u0e21\u0e2d\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e41\u0e21\u0e48\u0e19\u0e22\u0e33 \u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e \u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e22\u0e37\u0e14\u0e2b\u0e22\u0e38\u0e48\u0e19\u0e43\u0e19\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e17\u0e48\u0e2d<\/p>\n<p><img decoding=\"async\" class=\"wd-lazy-fade alignnone size-medium wp-image-45477\" src=\"https:\/\/www.vigert.com\/wp-content\/themes\/woodmart\/images\/lazy.svg\" data-src=\"https:\/\/www.vigert.com\/wp-content\/uploads\/2024\/02\/VIGERT-DW63NC-300x300.jpg\" alt=\"VIGERT DW63NC \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e31\u0e14\u0e17\u0e48\u0e2d\" width=\"300\" height=\"300\" srcset=\"\" data-srcset=\"https:\/\/www.vigert.com\/wp-content\/uploads\/2024\/02\/VIGERT-DW63NC-300x300.jpg 300w, https:\/\/www.vigert.com\/wp-content\/uploads\/2024\/02\/VIGERT-DW63NC-1024x1024.jpg 1024w, https:\/\/www.vigert.com\/wp-content\/uploads\/2024\/02\/VIGERT-DW63NC-150x150.jpg 150w, https:\/\/www.vigert.com\/wp-content\/uploads\/2024\/02\/VIGERT-DW63NC-768x768.jpg 768w, https:\/\/www.vigert.com\/wp-content\/uploads\/2024\/02\/VIGERT-DW63NC-12x12.jpg 12w, https:\/\/www.vigert.com\/wp-content\/uploads\/2024\/02\/VIGERT-DW63NC-600x600.jpg 600w, https:\/\/www.vigert.com\/wp-content\/uploads\/2024\/02\/VIGERT-DW63NC.jpg 1080w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img decoding=\"async\" class=\"wd-lazy-fade alignnone size-medium wp-image-45478\" src=\"https:\/\/www.vigert.com\/wp-content\/themes\/woodmart\/images\/lazy.svg\" data-src=\"https:\/\/www.vigert.com\/wp-content\/uploads\/2024\/02\/6ca2591223f9cba6d332fdcc61bca69-300x300.jpg\" alt=\"VIGERT DW63NC \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e31\u0e14\u0e17\u0e48\u0e2d\" width=\"300\" height=\"300\" srcset=\"\" data-srcset=\"https:\/\/www.vigert.com\/wp-content\/uploads\/2024\/02\/6ca2591223f9cba6d332fdcc61bca69-300x300.jpg 300w, https:\/\/www.vigert.com\/wp-content\/uploads\/2024\/02\/6ca2591223f9cba6d332fdcc61bca69-1024x1024.jpg 1024w, https:\/\/www.vigert.com\/wp-content\/uploads\/2024\/02\/6ca2591223f9cba6d332fdcc61bca69-150x150.jpg 150w, https:\/\/www.vigert.com\/wp-content\/uploads\/2024\/02\/6ca2591223f9cba6d332fdcc61bca69-768x768.jpg 768w, https:\/\/www.vigert.com\/wp-content\/uploads\/2024\/02\/6ca2591223f9cba6d332fdcc61bca69-12x12.jpg 12w, https:\/\/www.vigert.com\/wp-content\/uploads\/2024\/02\/6ca2591223f9cba6d332fdcc61bca69-600x600.jpg 600w, https:\/\/www.vigert.com\/wp-content\/uploads\/2024\/02\/6ca2591223f9cba6d332fdcc61bca69.jpg 1080w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img decoding=\"async\" class=\"wd-lazy-fade alignnone size-medium wp-image-45479\" src=\"https:\/\/www.vigert.com\/wp-content\/themes\/woodmart\/images\/lazy.svg\" data-src=\"https:\/\/www.vigert.com\/wp-content\/uploads\/2024\/02\/548aecaa8b220b6e312740a1616c63d-300x300.jpg\" alt=\"VIGERT DW63NC \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e31\u0e14\u0e17\u0e48\u0e2d\" width=\"300\" height=\"300\" srcset=\"\" data-srcset=\"https:\/\/www.vigert.com\/wp-content\/uploads\/2024\/02\/548aecaa8b220b6e312740a1616c63d-300x300.jpg 300w, https:\/\/www.vigert.com\/wp-content\/uploads\/2024\/02\/548aecaa8b220b6e312740a1616c63d-1024x1024.jpg 1024w, https:\/\/www.vigert.com\/wp-content\/uploads\/2024\/02\/548aecaa8b220b6e312740a1616c63d-150x150.jpg 150w, https:\/\/www.vigert.com\/wp-content\/uploads\/2024\/02\/548aecaa8b220b6e312740a1616c63d-768x768.jpg 768w, https:\/\/www.vigert.com\/wp-content\/uploads\/2024\/02\/548aecaa8b220b6e312740a1616c63d-12x12.jpg 12w, https:\/\/www.vigert.com\/wp-content\/uploads\/2024\/02\/548aecaa8b220b6e312740a1616c63d-600x600.jpg 600w, https:\/\/www.vigert.com\/wp-content\/uploads\/2024\/02\/548aecaa8b220b6e312740a1616c63d.jpg 1080w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>","protected":false},"excerpt":{"rendered":"<p>A VIGERT DW63NC Pipe Bending Machine is a piece of industrial equipment used to bend pipes or tubes into various<\/p>","protected":false},"featured_media":45479,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[7317],"product_tag":[7853],"class_list":["post-45387","product","type-product","status-publish","has-post-thumbnail","product_cat-pipe-bending-machine","product_tag-used-vigert-dw63nc-pipe-bending-machine-for-sale","first","instock","sale","shipping-taxable","purchasable","product-type-simple"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.vigert.com\/th\/wp-json\/wp\/v2\/product\/45387","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vigert.com\/th\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.vigert.com\/th\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vigert.com\/th\/wp-json\/wp\/v2\/comments?post=45387"}],"version-history":[{"count":0,"href":"https:\/\/www.vigert.com\/th\/wp-json\/wp\/v2\/product\/45387\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vigert.com\/th\/wp-json\/wp\/v2\/media\/45479"}],"wp:attachment":[{"href":"https:\/\/www.vigert.com\/th\/wp-json\/wp\/v2\/media?parent=45387"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.vigert.com\/th\/wp-json\/wp\/v2\/product_brand?post=45387"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.vigert.com\/th\/wp-json\/wp\/v2\/product_cat?post=45387"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.vigert.com\/th\/wp-json\/wp\/v2\/product_tag?post=45387"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}